{"id":31672,"date":"2020-11-09T13:15:28","date_gmt":"2020-11-09T12:15:28","guid":{"rendered":"https:\/\/dev.greatideasinaction.com\/dva\/?page_id=31672"},"modified":"2023-07-10T09:00:37","modified_gmt":"2023-07-10T07:00:37","slug":"adyuvantes","status":"publish","type":"page","link":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/","title":{"rendered":"Adyuvantes"},"content":{"rendered":"<section class=\"wpb-content-wrapper\">[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;1&#8243; bottom_padding=&#8221;1&#8243; back_color=&#8221;color-182462&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; css=&#8221;.vc_custom_1601377996268{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221; row_name=&#8221;3&#8243;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; gutter_size=&#8221;2&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][vc_custom_heading text_size=&#8221;h1&#8243; text_weight=&#8221;600&#8243; text_transform=&#8221;uppercase&#8221; text_height=&#8221;&#8221;]Adyuvantes[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-lxmt&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/1&#8243;][uncode_index el_id=&#8221;index-16599133&#8243; isotope_mode=&#8221;fitRows&#8221; loop=&#8221;size:All|order_by:title|order:ASC|post_type:page|tax_query:2581|taxonomy_count:10&#8243; gutter_size=&#8221;3&#8243; page_items=&#8221;media|featured|onpost|poster,title&#8221; screen_lg=&#8221;1000&#8243; screen_md=&#8221;600&#8243; screen_sm=&#8221;480&#8243; single_width=&#8221;3&#8243; single_back_color=&#8221;color-xsdn&#8221; single_overlay_opacity=&#8221;50&#8243; single_h_align=&#8221;center&#8221; single_padding=&#8221;2&#8243; single_title_dimension=&#8221;h3&#8243; single_title_weight=&#8221;600&#8243; single_title_transform=&#8221;uppercase&#8221; single_title_height=&#8221;&#8221; no_double_tap=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][uncode_block id=&#8221;31663&#8243;][\/vc_column][\/vc_row]\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;1&#8243; bottom_padding=&#8221;1&#8243; back_color=&#8221;color-182462&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; css=&#8221;.vc_custom_1601377996268{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221; row_name=&#8221;3&#8243;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;middle&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":14958,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.10 (Yoast SEO v20.10) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adyuvantes<\/title>\n<meta name=\"description\" content=\"Descubre nuestros adyuvantes de \u00faltima generaci\u00f3n que potencian la acci\u00f3n de los productos agr\u00edcolas y mejoran su eficacia en cada aplicaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adyuvantes\" \/>\n<meta property=\"og:description\" content=\"Descubre nuestros adyuvantes de \u00faltima generaci\u00f3n que potencian la acci\u00f3n de los productos agr\u00edcolas y mejoran su eficacia en cada aplicaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/\" \/>\n<meta property=\"og:site_name\" content=\"DVA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dvaglobal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T07:00:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/\",\"name\":\"Adyuvantes\",\"isPartOf\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/#website\"},\"datePublished\":\"2020-11-09T12:15:28+00:00\",\"dateModified\":\"2023-07-10T07:00:37+00:00\",\"description\":\"Descubre nuestros adyuvantes de \u00faltima generaci\u00f3n que potencian la acci\u00f3n de los productos agr\u00edcolas y mejoran su eficacia en cada aplicaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartera de Productos\",\"item\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adyuvantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/#website\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/\",\"name\":\"DVA\",\"description\":\"GO FURTHER. TOGETHER\",\"publisher\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/#organization\",\"name\":\"DVA\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg\",\"contentUrl\":\"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg\",\"width\":\"1000\",\"height\":\"1000\",\"caption\":\"DVA\"},\"image\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/co\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dvaglobal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adyuvantes","description":"Descubre nuestros adyuvantes de \u00faltima generaci\u00f3n que potencian la acci\u00f3n de los productos agr\u00edcolas y mejoran su eficacia en cada aplicaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/","og_locale":"es_ES","og_type":"article","og_title":"Adyuvantes","og_description":"Descubre nuestros adyuvantes de \u00faltima generaci\u00f3n que potencian la acci\u00f3n de los productos agr\u00edcolas y mejoran su eficacia en cada aplicaci\u00f3n.","og_url":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/","og_site_name":"DVA","article_publisher":"https:\/\/www.facebook.com\/dvaglobal","article_modified_time":"2023-07-10T07:00:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/","url":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/","name":"Adyuvantes","isPartOf":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/#website"},"datePublished":"2020-11-09T12:15:28+00:00","dateModified":"2023-07-10T07:00:37+00:00","description":"Descubre nuestros adyuvantes de \u00faltima generaci\u00f3n que potencian la acci\u00f3n de los productos agr\u00edcolas y mejoran su eficacia en cada aplicaci\u00f3n.","breadcrumb":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/adyuvantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.greatideasinaction.com\/dva\/co\/"},{"@type":"ListItem","position":2,"name":"Cartera de Productos","item":"https:\/\/dev.greatideasinaction.com\/dva\/co\/productos\/"},{"@type":"ListItem","position":3,"name":"Adyuvantes"}]},{"@type":"WebSite","@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/#website","url":"https:\/\/dev.greatideasinaction.com\/dva\/co\/","name":"DVA","description":"GO FURTHER. TOGETHER","publisher":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.greatideasinaction.com\/dva\/co\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/#organization","name":"DVA","url":"https:\/\/dev.greatideasinaction.com\/dva\/co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/#\/schema\/logo\/image\/","url":"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg","contentUrl":"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg","width":"1000","height":"1000","caption":"DVA"},"image":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dvaglobal"]}]}},"_links":{"self":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/pages\/31672"}],"collection":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/comments?post=31672"}],"version-history":[{"count":1,"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/pages\/31672\/revisions"}],"predecessor-version":[{"id":208642,"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/pages\/31672\/revisions\/208642"}],"up":[{"embeddable":true,"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/pages\/14958"}],"wp:attachment":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/co\/wp-json\/wp\/v2\/media?parent=31672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}