{"id":11354,"date":"2019-02-05T02:24:30","date_gmt":"2019-02-05T01:24:30","guid":{"rendered":"https:\/\/www.dva.endustry.de\/?page_id=11354"},"modified":"2020-10-11T03:59:26","modified_gmt":"2020-10-11T01:59:26","slug":"servicios","status":"publish","type":"page","link":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/","title":{"rendered":"Servicios"},"content":{"rendered":"<section class=\"wpb-content-wrapper\">[vc_row row_height_percent=&#8221;0&#8243; back_image=&#8221;11187&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; row_height_pixel=&#8221;200px&#8221;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;bottom&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-lxmt&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_use_pixel=&#8221;yes&#8221; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; css=&#8221;.vc_custom_1549418141261{padding-top: 25px !important;padding-bottom: 55px !important;}&#8221; column_width_pixel=&#8221;1200px&#8221;][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][vc_row_inner][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][vc_custom_heading text_size=&#8221;h1&#8243; text_weight=&#8221;400&#8243; text_height=&#8221;fontheight-357766&#8243; text_color=&#8221;accent&#8221; sub_lead=&#8221;yes&#8221; subheading=&#8221;Asistencia T\u00e9cnica especializada&#8221;]Optimizamos sus productos y procesos[\/vc_custom_heading][vc_separator sep_color=&#8221;color-gyho&#8221;][vc_column_text]<span style=\"font-size: 20px;\">DVA Mexicana pone a su disposici\u00f3n almacenes en La Ciudad de M\u00e9xico, Monterrey y Guadalajara para atender sus necesidades en tiempo y forma. Nuestro sistema log\u00edstico nos permite realizar entregas a su planta o almac\u00e9n en toda la Rep\u00fablica.Contamos con asistencia t\u00e9cnica mediante la cual podemos ayudarle a desarrollar un nuevo producto hasta antes del envase; incluyendo formulaci\u00f3n, balanceo de ingredientes, escalamiento, con lo que logramos reducir su tiempo de desarrollo y\/u optimizar un producto o proceso.<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shadow=&#8221;xs&#8221; width=&#8221;1\/2&#8243;][vc_custom_heading text_size=&#8221;h1&#8243; text_weight=&#8221;400&#8243; text_height=&#8221;fontheight-357766&#8243; text_color=&#8221;accent&#8221;]FARMAC\u00c8UTICA[\/vc_custom_heading][uncode_list larger=&#8221;yes&#8221; icon=&#8221;fa fa-arrow-right4&#8243; icon_color=&#8221;accent&#8221;]\n<ul>\n<li>Realizaci\u00f3n de pruebas de compresi\u00f3n para tabletas y capletas en 15 distintos tama\u00f1os.<\/li>\n<li>Dise\u00f1o y fabricaci\u00f3n de prototipos de tabletas recubiertas.<\/li>\n<li>Pruebas de Mezclado, desde 500 g hasta 3 kg.<\/li>\n<li>Dise\u00f1o de recubrimientos de acuerdo a sus requerimientos de color.<\/li>\n<li>Liberaci\u00f3n; protecci\u00f3n y funcionalidad.<\/li>\n<li>Apoyo en escalamiento y trasferencia de tecnolog\u00eda en su planta.<\/li>\n<li>Capacitaci\u00f3n en compresi\u00f3n y recubrimiento para operadores y qu\u00edmicos de formulaciones.<\/li>\n<li>Realizaci\u00f3n de pruebas de recubrimiento desde 300 g hasta 3 kg.<\/li>\n<li>Fabricaci\u00f3n de bases de color para fabricaci\u00f3n de capsulas de gelatina blanda.<\/li>\n<\/ul>\n[\/uncode_list][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shadow=&#8221;xs&#8221; width=&#8221;1\/2&#8243;][vc_custom_heading text_size=&#8221;h1&#8243; text_weight=&#8221;400&#8243; text_height=&#8221;fontheight-357766&#8243; text_color=&#8221;accent&#8221;]ALIMENTOS[\/vc_custom_heading][uncode_list icon=&#8221;fa fa-arrow-right4&#8243; icon_color=&#8221;accent&#8221;]\n<ul>\n<li>Desarrollo o dise\u00f1o de productos principalmente en las \u00e1reas: Bebidas, C\u00e1rnicos y L\u00e1cteos.<\/li>\n<li>Soporte T\u00e9cnico personalizado.<\/li>\n<li>Capacitaciones en diferentes \u00e1reas para nuestros clientes.<\/li>\n<li><strong>Dise\u00f1o de sistemas funcionales, para las \u00e1reas de:<\/strong>\n<ul>\n<li>Bebidas: mejorar cuerpo \u201cSmoothfeel\u201d, mejorar o balancear propiedades nutricionales, mejorar vida de anaquel reduciendo precipitaciones, floculaciones, etc.<\/li>\n<li>C\u00e1rnicos: optimizar costos de f\u00f3rmula, optimizar costos por procesos, mejorar vida \u00fatil, reducci\u00f3n de sin\u00e9resis en producto terminado, mejorar rebanabilidad, mejorar textura, mejorar rendimiento, etc.<\/li>\n<li>L\u00e1cteos: Optimizar costos de f\u00f3rmula, optimizar condiciones de proceso, mejorar texturas, optimizar vida de anaquel, reducci\u00f3n de sin\u00e9resis en: Yogurt, Quesos, Cremas<\/li>\n<li>Aderezos, Confiter\u00eda, panificaci\u00f3n, salsas: mejoramos textura, optimizamos costos de f\u00f3rmulas, dise\u00f1o de productos acorde a necesidades.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n[\/uncode_list][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;accent&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; css=&#8221;.vc_custom_1549458380786{padding-top: 45px !important;padding-bottom: 55px !important;}&#8221;][vc_column width=&#8221;1\/1&#8243;][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; shape_dividers=&#8221;&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shadow=&#8221;xs&#8221; width=&#8221;1\/4&#8243;][vc_column_text]\n<h3>DESARROLLO<\/h3>\n<p>Apoyo en el desarrollo de formulaciones o propuestas de formulaci\u00f3n para que el cliente las pruebe en sus instalaciones.[\/vc_column_text][vc_separator sep_color=&#8221;color-gyho&#8221;][vc_column_text]\n<h3>APLICACI\u00d3N<\/h3>\n<p>Aplicaci\u00f3n de ingredientes.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shadow=&#8221;xs&#8221; width=&#8221;1\/4&#8243;][vc_column_text]\n<h3>PROTOTIPOS<\/h3>\n<p>Pruebas para presentar prototipo del producto en la forma farmac\u00e9utica tableta y fabricar los lotes para estabilidad hasta la fase de recubrimiento.[\/vc_column_text][vc_separator sep_color=&#8221;color-gyho&#8221;][vc_column_text]\n<h3>OPTIMIZACI\u00d3N<\/h3>\n<p>Optimizaci\u00f3n de uso de aditivos.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shadow=&#8221;xs&#8221; width=&#8221;1\/4&#8243;][vc_column_text]\n<h3>DISE\u00d1O<\/h3>\n<p>Dise\u00f1o de productos terminados justo antes del empaque.[\/vc_column_text][vc_separator sep_color=&#8221;color-gyho&#8221;][vc_column_text]\n<h3>ASESOR\u00cdA<\/h3>\n<p>Asesor\u00eda t\u00e9cnica.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; shadow=&#8221;xs&#8221; width=&#8221;1\/4&#8243;][vc_column_text]\n<h3>BALANCEO<\/h3>\n<p>Balanceo de formulaciones.[\/vc_column_text][vc_separator sep_color=&#8221;color-gyho&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_use_pixel=&#8221;yes&#8221; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; column_width_pixel=&#8221;1100px&#8221;][vc_column width=&#8221;1\/1&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243;][uncode_block id=&#8221;79599&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; back_image=&#8221;11187&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; row_height_pixel=&#8221;200px&#8221;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;bottom&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][\/vc_column][\/vc_row][vc_row [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11092,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.10 (Yoast SEO v20.10) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Servicios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios\" \/>\n<meta property=\"og:description\" content=\"[vc_row row_height_percent=&#8221;0&#8243; back_image=&#8221;11187&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; row_height_pixel=&#8221;200px&#8221;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;bottom&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][\/vc_column][\/vc_row][vc_row [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/\" \/>\n<meta property=\"og:site_name\" content=\"DVA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dvaglobal\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-11T01:59:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/07\/servicios-dva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/\",\"name\":\"Servicios\",\"isPartOf\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#website\"},\"datePublished\":\"2019-02-05T01:24:30+00:00\",\"dateModified\":\"2020-10-11T01:59:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#website\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/\",\"name\":\"DVA\",\"description\":\"GO FURTHER. TOGETHER\",\"publisher\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#organization\",\"name\":\"DVA\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg\",\"contentUrl\":\"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg\",\"width\":\"1000\",\"height\":\"1000\",\"caption\":\"DVA\"},\"image\":{\"@id\":\"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dvaglobal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Servicios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/","og_locale":"es_MX","og_type":"article","og_title":"Servicios","og_description":"[vc_row row_height_percent=&#8221;0&#8243; back_image=&#8221;11187&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; row_height_pixel=&#8221;200px&#8221;][vc_column column_width_percent=&#8221;100&#8243; position_vertical=&#8221;bottom&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243;][\/vc_column][\/vc_row][vc_row [&hellip;]","og_url":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/","og_site_name":"DVA","article_publisher":"https:\/\/www.facebook.com\/dvaglobal","article_modified_time":"2020-10-11T01:59:26+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/07\/servicios-dva.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/","url":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/","name":"Servicios","isPartOf":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#website"},"datePublished":"2019-02-05T01:24:30+00:00","dateModified":"2020-10-11T01:59:26+00:00","breadcrumb":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/servicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/"},{"@type":"ListItem","position":2,"name":"Servicios"}]},{"@type":"WebSite","@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#website","url":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/","name":"DVA","description":"GO FURTHER. TOGETHER","publisher":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#organization","name":"DVA","url":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#\/schema\/logo\/image\/","url":"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg","contentUrl":"https:\/\/dev.greatideasinaction.com\/dva\/wp-content\/uploads\/2020\/05\/dva-group-logo.svg","width":"1000","height":"1000","caption":"DVA"},"image":{"@id":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dvaglobal"]}]}},"_links":{"self":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/pages\/11354"}],"collection":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/comments?post=11354"}],"version-history":[{"count":0,"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/pages\/11354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/media\/11092"}],"wp:attachment":[{"href":"https:\/\/dev.greatideasinaction.com\/dva\/mx\/wp-json\/wp\/v2\/media?parent=11354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}